{"id":86399,"date":"2025-08-18T17:37:05","date_gmt":"2025-08-18T15:37:05","guid":{"rendered":"https:\/\/jafep.com\/sistema-anti-corrosao-jafep-para-atingir-o-ambiente-c5-high\/"},"modified":"2025-08-18T17:37:06","modified_gmt":"2025-08-18T15:37:06","slug":"sistema-anti-corrosao-jafep-para-atingir-o-ambiente-c5-high","status":"publish","type":"post","link":"https:\/\/jafep.com\/pt-pt\/sistema-anti-corrosao-jafep-para-atingir-o-ambiente-c5-high\/","title":{"rendered":"Sistema anti-corros\u00e3o Jafep para atingir o ambiente C5 High"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"261\" height=\"400\" src=\"https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Imprimacion-Epoxi-Anticorrosiva-JAFEP-261x400-1.png\" alt=\"en Pinturas Jafep\" class=\"wp-image-84422\" title=\"en Pinturas Jafep\" srcset=\"https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Imprimacion-Epoxi-Anticorrosiva-JAFEP-261x400-1.png 261w, https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Imprimacion-Epoxi-Anticorrosiva-JAFEP-261x400-1-196x300.png 196w, https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Imprimacion-Epoxi-Anticorrosiva-JAFEP-261x400-1-98x150.png 98w\" sizes=\"(max-width: 261px) 100vw, 261px\" \/><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img decoding=\"async\" width=\"271\" height=\"400\" src=\"https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Esmalte-Poliuretano-JAFEP-271x400-1.png\" alt=\"en Pinturas Jafep\" class=\"wp-image-84426\" title=\"en Pinturas Jafep\" srcset=\"https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Esmalte-Poliuretano-JAFEP-271x400-1.png 271w, https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Esmalte-Poliuretano-JAFEP-271x400-1-203x300.png 203w, https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/Esmalte-Poliuretano-JAFEP-271x400-1-102x150.png 102w\" sizes=\"(max-width: 271px) 100vw, 271px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Prim\u00e1rio ep\u00f3xi anti-corrosivo e esmalte de poliuretano de dois componentes<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Se necessitas de uma prote\u00e7\u00e3o eficaz contra ambientes extremos, na <strong>Jafep<\/strong> temos a solu\u00e7\u00e3o perfeita para ti com estes dois produtos: <strong>Prim\u00e1rio Ep\u00f3xi Anticorrosivo<\/strong> e <strong>Esmalte de Poliuretano de dois componentes<\/strong>. E n\u00e3o somos n\u00f3s que o dizemos, mas depois de cumprirmos os exigentes requisitos, somos aprovados pela norma <strong>UNE-EN ISO 12944-6:2018<\/strong> para a corros\u00e3o atmosf\u00e9rica. N\u00f3s contamos-te!  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Prote\u00e7\u00e3o contra a corros\u00e3o: Solu\u00e7\u00f5es eficientes para todos os ambientes<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">A corros\u00e3o \u00e9 o <strong>processo de degrada\u00e7\u00e3o de materiais<\/strong>, principalmente metais, como resultado de uma rea\u00e7\u00e3o com o seu ambiente, como o ar, a \u00e1gua ou produtos qu\u00edmicos. Este fen\u00f3meno \u00e9 uma das principais amea\u00e7as \u00e0s estruturas met\u00e1licas, pois pode levar \u00e0 deteriora\u00e7\u00e3o e \u00e0 perda de funcionalidade dos componentes. Para <strong>combater a corros\u00e3o<\/strong>, s\u00e3o utilizados sistemas de prote\u00e7\u00e3o espec\u00edficos em fun\u00e7\u00e3o do tipo de ambiente e da intensidade da exposi\u00e7\u00e3o.  <\/p>\n\n<p class=\"wp-block-paragraph\">Hoje vamos focar-nos em quais s\u00e3o os sistemas de prote\u00e7\u00e3o anticorrosiva e as suas categorias, de acordo com a norma acima mencionada, quais s\u00e3o os produtos adequados e a sua correta aplica\u00e7\u00e3o para obter os resultados esperados.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Como \u00e9 que a corros\u00e3o afecta os materiais?<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Nos metais ferrosos, como o a\u00e7o, a corros\u00e3o pode ocorrer sob a forma de <strong>ferrugem<\/strong>, enfraquecendo a sua estrutura e comprometendo a sua seguran\u00e7a.<\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>Factores que influenciam a corros\u00e3o:<\/strong><\/li>\n<\/ol>\n\n<ul class=\"wp-block-list\">\n<li><strong>Estado da superf\u00edcie<\/strong>: As superf\u00edcies limpas ou rugosas afectam a taxa de corros\u00e3o.<\/li>\n\n\n\n<li><strong>Temperatura e tempo<\/strong>: O aumento da temperatura acelera a corros\u00e3o.<\/li>\n\n\n\n<li><strong>Diferen\u00e7a de potencial<\/strong>: \u00c1reas de potencial el\u00e9trico diferente aumentam o processo.<\/li>\n\n\n\n<li><strong>Eros\u00e3o<\/strong>: O desgaste mec\u00e2nico aumenta a exposi\u00e7\u00e3o das superf\u00edcies a agentes corrosivos.<\/li>\n\n\n\n<li><strong>Polui\u00e7\u00e3o ambiental<\/strong>: A presen\u00e7a de poluentes, como o di\u00f3xido de enxofre ou o sal, acelera a corros\u00e3o.<\/li>\n\n\n\n<li><strong>Factores biol\u00f3gicos<\/strong>: Os microrganismos, como as bact\u00e9rias, podem contribuir para a deteriora\u00e7\u00e3o.<\/li>\n<\/ul>\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Corros\u00e3o atmosf\u00e9rica: <\/strong>Ocorre quando o metal \u00e9 exposto \u00e0 atmosfera, onde uma camada de humidade (invis\u00edvel a olho nu) actua como meio para o processo corrosivo. A taxa de corros\u00e3o depende da <strong>humidade relativa<\/strong>, da <strong>condensa\u00e7\u00e3o<\/strong> e da <strong>contamina\u00e7\u00e3o<\/strong> do ar. <\/li>\n<\/ol>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"311\" height=\"400\" src=\"https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/barandilla-sin-imprimacion-corrosiva-JAFEP-311x400-1.jpg\" alt=\"en Pinturas Jafep\" class=\"wp-image-84431\" title=\"en Pinturas Jafep\" srcset=\"https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/barandilla-sin-imprimacion-corrosiva-JAFEP-311x400-1.jpg 311w, https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/barandilla-sin-imprimacion-corrosiva-JAFEP-311x400-1-233x300.jpg 233w, https:\/\/jafep.com\/wp-content\/uploads\/2025\/03\/barandilla-sin-imprimacion-corrosiva-JAFEP-311x400-1-117x150.jpg 117w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>  Categorias de corrosividade de acordo com a norma UNE-EN ISO 12944-6:2018:<\/strong><\/li>\n<\/ol>\n\n<ul class=\"wp-block-list\">\n<li><strong>C1 (Baixa corros\u00e3o)<\/strong>: Ambientes secos, como escrit\u00f3rios e habita\u00e7\u00f5es com aquecimento.<\/li>\n\n\n\n<li><strong>C2 (Baixa corros\u00e3o)<\/strong>: \u00c1reas interiores com baixa contamina\u00e7\u00e3o, tais como armaz\u00e9ns.<\/li>\n\n\n\n<li><strong>C3 (corros\u00e3o moderada)<\/strong>: Zonas urbanas e industriais, como f\u00e1bricas de alimentos ou lavandarias.<\/li>\n\n\n\n<li><strong>C4 (Corros\u00e3o elevada)<\/strong>: Zonas industriais e costeiras com salinidade moderada, como estaleiros navais e piscinas.<\/li>\n\n\n\n<li><strong>C5 (Corros\u00e3o muito elevada)<\/strong>: Ambientes marinhos e zonas industriais com elevada humidade e polui\u00e7\u00e3o.<\/li>\n\n\n\n<li><strong>CX (Extreme Corrosion)<\/strong>: Zonas mar\u00edtimas ou industriais com ambientes muito agressivos.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Ensaios de corros\u00e3o de acordo com a norma UNE-EN ISO 12944-6:2018<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Para garantir a efic\u00e1cia dos sistemas de prote\u00e7\u00e3o, \u00e9 necess\u00e1rio realizar testes detalhados que simulem condi\u00e7\u00f5es reais de corros\u00e3o. Alguns dos testes mais comuns incluem: <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>N\u00e9voa salina (UNE-EN ISO 9227)<\/strong>.<\/li>\n\n\n\n<li><strong>Resist\u00eancia \u00e0 humidade (UNE-EN ISO 6270-1:2019)<\/strong>.<\/li>\n\n\n\n<li><strong>Grau de forma\u00e7\u00e3o de bolhas, oxida\u00e7\u00e3o, fissura\u00e7\u00e3o e descama\u00e7\u00e3o (UNE-EN ISO 4628).<\/strong><\/li>\n\n\n\n<li><strong>Medi\u00e7\u00e3o da espessura e corte por grelha (UNE-EN ISO 2409)<\/strong>.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Produtos de prote\u00e7\u00e3o contra a corros\u00e3o Jafep<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">E esses foram todos os testes que nossos produtos tiveram que passar, a fim de obter a certifica\u00e7\u00e3o concedida pela norma <strong>UNE-EN ISO 12944-6: 2018<\/strong>, endossando o poder de prote\u00e7\u00e3o contra a corros\u00e3o do <strong>sistema de pintura<\/strong> <strong>Jafep<\/strong>. Este sistema, composto pelo <strong>Prim\u00e1rio Ep\u00f3xi Anticorrosivo de Dois Componentes<\/strong> e pelo <strong>Esmalte de Poliuretano de Dois Componentes<\/strong>, demonstrou ser altamente eficaz quando aplicado em conjunto, proporcionando uma prote\u00e7\u00e3o fundamental \u00e0s tuas estruturas met\u00e1licas de acordo com as categorias de corros\u00e3o acima mencionadas. <\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>Prim\u00e1rio epox\u00eddico anticorrosivo de dois componentes:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Vantagens:<\/strong> Elevada resist\u00eancia \u00e0 corros\u00e3o e \u00e0 proje\u00e7\u00e3o de sal, bem como boas carater\u00edsticas mec\u00e2nicas e resist\u00eancia qu\u00edmica.<\/li>\n\n\n\n<li><strong>Aplica\u00e7\u00e3o:<\/strong> Ideal para superf\u00edcies met\u00e1licas que necessitem de elevada resist\u00eancia qu\u00edmica. Recomenda-se a aplica\u00e7\u00e3o em superf\u00edcies limpas e secas, com pincel, rolo ou spray. <\/li>\n\n\n\n<li><strong>Ambientes recomendados:<\/strong> C4: F\u00e1bricas de produtos qu\u00edmicos, estaleiros navais, piscinas; C5: Zonas costeiras e mar\u00edtimas com elevada salinidade.<\/li>\n\n\n\n<li><strong>Propriedades:<\/strong> Elevada cobertura; resist\u00eancia \u00e0 salinidade (250 horas); ideal como base para acabamentos de poliuretano.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Esmalte de poliuretano de dois componentes:<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Vantagens:<\/strong> Elevado brilho e reten\u00e7\u00e3o da cor. Elevada resist\u00eancia qu\u00edmica e ao ar livre. Excelente ader\u00eancia em superf\u00edcies met\u00e1licas.  <\/li>\n\n\n\n<li><strong>Aplica\u00e7\u00e3o:<\/strong> Recomendado para superf\u00edcies met\u00e1licas e trabalhos em metal (alum\u00ednio). A aplica\u00e7\u00e3o deve ser efectuada no prazo de 24 horas ap\u00f3s a aplica\u00e7\u00e3o do prim\u00e1rio epox\u00eddico. <\/li>\n\n\n\n<li><strong>Ambientes recomendados:<\/strong> C4: Zonas industriais e costeiras de salinidade moderada; C5: Zonas muito polu\u00eddas e de elevada salinidade.<\/li>\n\n\n\n<li><strong>Propriedades:<\/strong> Elevada estabilidade da cor e do brilho e boa resist\u00eancia \u00e0 abras\u00e3o e aos produtos qu\u00edmicos dom\u00e9sticos.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><strong>Aplica\u00e7\u00e3o correta do sistema de pintura Jafep para garantir a prote\u00e7\u00e3o<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Como mencion\u00e1mos anteriormente, este <strong>sistema de pintura<\/strong>, que utiliza primeiro o <strong>Prim\u00e1rio Ep\u00f3xi Anticorrosivo<\/strong> e depois o <strong>Esmalte de Poliuretano Jafep<\/strong>, demonstrou excelentes resultados em ambientes corrosivos <strong>C5 <\/strong>(ambientes mar\u00edtimos e zonas industriais h\u00famidas) e<strong> C4 <\/strong>(zonas costeiras e zonas industriais moderadas), cumprindo os requisitos estabelecidos na norma <strong>UNE-EN ISO 12944-6:2018<\/strong>. Os resultados obtidos s\u00e3o detalhados de seguida: <\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>C5: <\/strong>Em ambientes mar\u00edtimos e zonas industriais com elevada humidade e polui\u00e7\u00e3o, o sistema de pintura Jafep prim\u00e1rio ep\u00f3xi anti-corrosivo + Jafep esmalte poliuretano obteve um resultado de prote\u00e7\u00e3o<strong> ELEVADO<\/strong>.<\/li>\n\n\n\n<li><strong>C4: <\/strong>Em zonas industriais e costeiras com salinidade moderada, como estaleiros navais e piscinas, o sistema de pintura Jafep prim\u00e1rio ep\u00f3xi anticorrosivo + Jafep esmalte poliuretano obteve um resultado de prote\u00e7\u00e3o<strong> MUITO ALTO<\/strong>.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">Seguindo as diretrizes de aplica\u00e7\u00e3o e escolhendo o <strong>sistema de pintura<\/strong> <strong>Jafep<\/strong> de acordo com a categoria de corrosividade, as tuas estruturas met\u00e1licas ficar\u00e3o eficazmente protegidas contra a corros\u00e3o durante anos.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"386\" height=\"271\" src=\"https:\/\/www.jafep.com\/wp-content\/uploads\/2025\/03\/aplicacion-recomendada-para-ensayos-de-corrosion.png\" alt=\"Aplica&#xE7;&#xE3;o recomendada para testes de corros&#xE3;o\" class=\"wp-image-14511\" title=\"en Pinturas Jafep\"><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><br\/><br\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prim\u00e1rio ep\u00f3xi anti-corrosivo e esmalte de poliuretano de dois componentes Se necessitas de uma prote\u00e7\u00e3o eficaz contra ambientes extremos, na Jafep temos a solu\u00e7\u00e3o perfeita para ti com estes dois produtos: Prim\u00e1rio Ep\u00f3xi Anticorrosivo e Esmalte de Poliuretano de dois componentes. E n\u00e3o somos n\u00f3s que o dizemos, mas depois de cumprirmos os exigentes requisitos,&#8230;<\/p>\n","protected":false},"author":25,"featured_media":83824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"class_list":["post-86399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria-pt-pt","th-blog blog-single has-post-thumbnail"],"acf":[],"_links":{"self":[{"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/posts\/86399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=86399"}],"version-history":[{"count":1,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/posts\/86399\/revisions"}],"predecessor-version":[{"id":86404,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/posts\/86399\/revisions\/86404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/media\/83824"}],"wp:attachment":[{"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=86399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=86399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jafep.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=86399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}